{"id":4151,"date":"2017-02-20T09:38:38","date_gmt":"2017-02-20T06:38:38","guid":{"rendered":"https:\/\/www.have-fun.gr\/8i-diimerida-ekthesi-epichirimatikotita-epikinonia-ygias\/"},"modified":"2017-07-30T16:02:28","modified_gmt":"2017-07-30T13:02:28","slug":"8i-diimerida-ekthesi-epichirimatikotita-epikinonia-ygias","status":"publish","type":"post","link":"https:\/\/www.have-fun.gr\/en\/8i-diimerida-ekthesi-epichirimatikotita-epikinonia-ygias\/","title":{"rendered":"8th Workshop + &#8220;Entrepreneurship &#038; Health Communication&#8221; Exhibition"},"content":{"rendered":"<p>We thank the following companies for the trust of the planning of promotion and construction of exhibition kiosks:<\/p>\n<div class=\"text_exposed_show\">\n<p>&#8211; CHARAMI S.A.<br \/>\n&#8211; ROCHE<br \/>\n&#8211; VALEANT<\/p>\n<div id=\"metaslider-id-3467\" style=\"width: 100%; margin: 0 auto;\" class=\"ml-slider-3-110-0 metaslider metaslider-responsive metaslider-3467 ml-slider has-dots-nav ms-theme-default\" role=\"region\" aria-label=\"Epixeirimatikotita k Epikoinonia\" data-height=\"600\" data-width=\"700\">\n    <div id=\"metaslider_container_3467\">\n        <ul id='metaslider_3467' class='rslides'>\n            <li aria-roledescription='slide' aria-labelledby='slide-0'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"695\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803046_1050922111632697_2339278412724510815_n.jpg\" class=\"slider-3467 slide-3474 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803046_1050922111632697_2339278412724510815_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803046_1050922111632697_2339278412724510815_n-768x556.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803046_1050922111632697_2339278412724510815_n-700x507.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-1'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/10391621_1050922568299318_6161063342210825566_n.jpg\" class=\"slider-3467 slide-3468 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/10391621_1050922568299318_6161063342210825566_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/10391621_1050922568299318_6161063342210825566_n-768x576.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/10391621_1050922568299318_6161063342210825566_n-800x600.jpg 800w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/10391621_1050922568299318_6161063342210825566_n-700x525.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-2'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1193\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16700389_1006412756126582_8139729834840888694_o.jpg\" class=\"slider-3467 slide-4861 msDefaultImage\" alt=\"\" rel=\"\" title=\"16700389_1006412756126582_8139729834840888694_o\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16700389_1006412756126582_8139729834840888694_o.jpg 2048w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16700389_1006412756126582_8139729834840888694_o-500x291.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16700389_1006412756126582_8139729834840888694_o-768x447.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16700389_1006412756126582_8139729834840888694_o-700x408.jpg 700w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-3'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1214\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16804023_1006412749459916_6851821987291471332_o.jpg\" class=\"slider-3467 slide-4862 msDefaultImage\" alt=\"\" rel=\"\" title=\"16804023_1006412749459916_6851821987291471332_o\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16804023_1006412749459916_6851821987291471332_o.jpg 2048w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16804023_1006412749459916_6851821987291471332_o-500x296.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16804023_1006412749459916_6851821987291471332_o-768x455.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16804023_1006412749459916_6851821987291471332_o-700x415.jpg 700w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-4'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1365\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16836383_1008026532631871_6096995644329088505_o.jpg\" class=\"slider-3467 slide-4864 msDefaultImage\" alt=\"\" rel=\"\" title=\"16836383_1008026532631871_6096995644329088505_o\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16836383_1008026532631871_6096995644329088505_o.jpg 2048w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16836383_1008026532631871_6096995644329088505_o-500x333.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16836383_1008026532631871_6096995644329088505_o-768x512.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16836383_1008026532631871_6096995644329088505_o-700x467.jpg 700w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-5'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12799119_1050922274966014_5273371397191740472_n.jpg\" class=\"slider-3467 slide-3475 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12799119_1050922274966014_5273371397191740472_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12799119_1050922274966014_5273371397191740472_n-768x512.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12799119_1050922274966014_5273371397191740472_n-700x467.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-6'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806104_1050922118299363_5388999173853483415_n.jpg\" class=\"slider-3467 slide-3472 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806104_1050922118299363_5388999173853483415_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806104_1050922118299363_5388999173853483415_n-768x512.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806104_1050922118299363_5388999173853483415_n-700x467.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-7'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"639\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806211_1050922941632614_9176201878011189452_n.jpg\" class=\"slider-3467 slide-3471 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806211_1050922941632614_9176201878011189452_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806211_1050922941632614_9176201878011189452_n-768x511.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12806211_1050922941632614_9176201878011189452_n-700x466.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-8'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"639\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12794396_1050924928299082_1402341049797675974_n.jpg\" class=\"slider-3467 slide-3478 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12794396_1050924928299082_1402341049797675974_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12794396_1050924928299082_1402341049797675974_n-768x511.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12794396_1050924928299082_1402341049797675974_n-700x466.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-9'><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1491\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16825821_1006412766126581_7013285638928834807_o.jpg\" class=\"slider-3467 slide-4863 msDefaultImage\" alt=\"\" rel=\"\" title=\"16825821_1006412766126581_7013285638928834807_o\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16825821_1006412766126581_7013285638928834807_o.jpg 2048w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16825821_1006412766126581_7013285638928834807_o-500x364.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16825821_1006412766126581_7013285638928834807_o-768x559.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/16825821_1006412766126581_7013285638928834807_o-700x510.jpg 700w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-10'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"624\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12795334_1050922734965968_9048777594582420196_n.jpg\" class=\"slider-3467 slide-3477 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12795334_1050922734965968_9048777594582420196_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12795334_1050922734965968_9048777594582420196_n-768x499.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12795334_1050922734965968_9048777594582420196_n-400x260.jpg 400w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12795334_1050922734965968_9048777594582420196_n-700x455.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-11'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"639\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12809633_1050924264965815_6344927015196823145_n.jpg\" class=\"slider-3467 slide-3470 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12809633_1050924264965815_6344927015196823145_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12809633_1050924264965815_6344927015196823145_n-768x511.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12809633_1050924264965815_6344927015196823145_n-700x466.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-12'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12798958_1050922431632665_5379510355156284166_n.jpg\" class=\"slider-3467 slide-3476 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12798958_1050922431632665_5379510355156284166_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12798958_1050922431632665_5379510355156284166_n-768x512.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12798958_1050922431632665_5379510355156284166_n-700x467.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-13'><img loading=\"lazy\" decoding=\"async\" width=\"722\" height=\"720\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803132_1050922381632670_6087356928045611956_n.jpg\" class=\"slider-3467 slide-3473 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803132_1050922381632670_6087356928045611956_n.jpg 722w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803132_1050922381632670_6087356928045611956_n-500x500.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12803132_1050922381632670_6087356928045611956_n-700x698.jpg 700w\" sizes=\"auto, (max-width: 722px) 100vw, 722px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-14'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"624\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/IMG_0551.jpg\" class=\"slider-3467 slide-4865 msDefaultImage\" alt=\"\" rel=\"\" title=\"IMG_0551\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/IMG_0551.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/IMG_0551-500x325.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/IMG_0551-768x499.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/IMG_0551-400x260.jpg 400w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/IMG_0551-700x455.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-15'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12814683_1050924114965830_5069886093879107347_n.jpg\" class=\"slider-3467 slide-3469 msDefaultImage\" alt=\"\" rel=\"\" title=\"\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12814683_1050924114965830_5069886093879107347_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12814683_1050924114965830_5069886093879107347_n-768x512.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2016\/12\/12814683_1050924114965830_5069886093879107347_n-700x467.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-16'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12799260_770208529747007_6107632741329120671_n.jpg\" class=\"slider-3467 slide-4859 msDefaultImage\" alt=\"\" rel=\"\" title=\"12799260_770208529747007_6107632741329120671_n\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12799260_770208529747007_6107632741329120671_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12799260_770208529747007_6107632741329120671_n-500x333.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12799260_770208529747007_6107632741329120671_n-768x512.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12799260_770208529747007_6107632741329120671_n-700x467.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n            <li style='display: none;' aria-roledescription='slide' aria-labelledby='slide-17'><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12821558_770208549747005_2791946023763839631_n.jpg\" class=\"slider-3467 slide-4860 msDefaultImage\" alt=\"\" rel=\"\" title=\"12821558_770208549747005_2791946023763839631_n\" srcset=\"https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12821558_770208549747005_2791946023763839631_n.jpg 960w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12821558_770208549747005_2791946023763839631_n-500x333.jpg 500w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12821558_770208549747005_2791946023763839631_n-768x512.jpg 768w, https:\/\/www.have-fun.gr\/wp-content\/uploads\/2018\/07\/12821558_770208549747005_2791946023763839631_n-700x467.jpg 700w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/li>\n        <\/ul>\n        \n    <\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>We thank the following companies for the trust of the planning of promotion and construction of exhibition kiosks: &#8211; CHARAMI S.A. &#8211; ROCHE &#8211; VALEANT<\/p>\n","protected":false},"author":1,"featured_media":1913,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"categories":[115],"tags":[],"class_list":["post-4151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photography-en"],"_links":{"self":[{"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/posts\/4151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/comments?post=4151"}],"version-history":[{"count":0,"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/posts\/4151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/media\/1913"}],"wp:attachment":[{"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/media?parent=4151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/categories?post=4151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.have-fun.gr\/en\/wp-json\/wp\/v2\/tags?post=4151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}